{"id":25891,"date":"2025-03-05T11:15:41","date_gmt":"2025-03-05T10:15:41","guid":{"rendered":"https:\/\/www.kantersanimalhealth.com\/informativa-sulla-privacy\/"},"modified":"2025-09-05T15:03:40","modified_gmt":"2025-09-05T14:03:40","slug":"informativa-sulla-privacy","status":"publish","type":"page","link":"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/","title":{"rendered":"Informativa sulla privacy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25891\" class=\"elementor elementor-25891 elementor-7159\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1466aeb elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1466aeb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a945e06\" data-id=\"a945e06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88bfd72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88bfd72\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-832173c\" data-id=\"832173c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0beaf1c elementor-widget elementor-widget-heading\" data-id=\"0beaf1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Informativa sulla privacy<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85ae149 elementor-widget elementor-widget-heading\" data-id=\"85ae149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Condizioni d'uso del presente sito web<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29af564 elementor-widget elementor-widget-text-editor\" data-id=\"29af564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kanters Special Products B.V.<br>Con sede in:<br>De Stater 32<br>5737 RV Lieshout<\/p><p>Paesi Bassi, \u00e8 responsabile del trattamento dei dati personali come specificato nella presente Informativa sulla privacy.<br><br><\/p><p>Dettagli di contatto:<br><a href=\"https:\/\/www.kantersanimalhealth.com\/it\/\">https:\/\/www.kantersanimalhealth.com\/<br><\/a>De Stater 32<br>5737 RV Lieshout<br>Paesi Bassi +31 (0) 499-425 600<\/p><p>Numero di registrazione camerale: 17076311<\/p><p>Il nostro referente per il regolamento generale sulla protezione dei dati (GDPR) \u00e8 raggiungibile all&#8217;indirizzo <a href=\"mailto:info@kanters.nl\">info@kanters.nl<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcf6fb8 elementor-widget elementor-widget-accordion\" data-id=\"dcf6fb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2311\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">1. Dati personali trattati<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2311\"><p><strong>Kanters Special Products B.V. pu\u00f2 trattare i dati personali dell&#8217;utente perch\u00e9:<\/strong><\/p>\n<ul>\n<li>l&#8217;utente utilizza i servizi di Kanters Special Products B.V.,<\/li>\n<li>e\/o l&#8217;utente fornisce questi dati accettando la presente Informativa sulla privacy al momento della compilazione di un modulo di contatto sul sito web.<\/li>\n<\/ul>\n<p><strong>I dati personali trattati da Kanters includono:<\/strong><\/p>\n<ul>\n<li>Dati aziendali<\/li>\n<li>Nome e cognome<\/li>\n<li>Numero di telefono<\/li>\n<li>Numero di fax<\/li>\n<li>Indirizzo e-mail<\/li>\n<li>Dati sull&#8217;attivit\u00e0 dell&#8217;utente sul sito web<\/li>\n<li>Indirizzo<\/li>\n<li> Indirizzo IP<\/li>\n<li>Settore di attivit\u00e0<\/li>\n<li>Settore secondario<\/li>\n<li>Numero UBN<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2312\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2312\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2. Dati personali particolari e\/o sensibili trattati<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2312\"><p>Il nostro sito e\/o servizio web non intende raccogliere dati personali di visitatori di et\u00e0 inferiore ai 16 anni senza il consenso dei genitori o tutori. Poich\u00e9 non possiamo verificare l&#8217;et\u00e0 degli utenti, invitiamo i genitori a monitorare l&#8217;attivit\u00e0 online dei propri figli per prevenire la raccolta non autorizzata di dati. Se l&#8217;utente ritiene che Kanters abbia raccolto dati personali di un minore senza consenso, \u00e8 invitato a contattarci all&#8217;indirizzo <a href=\"mailto:info@kanters.nl\">info@kanters.nl<\/a> per richiederne la cancellazione.    <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2313\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2313\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">3. Scopo e basi giuridiche del trattamento dei dati personali<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2313\"><p>Kanters Special Products B.V. tratta i dati personali dell&#8217;utente per contattarlo telefonicamente su sua richiesta e\/o per contattarlo per iscritto (via e-mail o posta) qualora non fosse possibile raggiungerlo telefonicamente.<\/p>\n<p>Kanters Special Products B.V. tratta i dati personali dell&#8217;utente per le seguenti finalit\u00e0:<\/p>\n<ul>\n<li>Gestione ordini<\/li>\n<li>Attivit\u00e0 di marketing<\/li>\n<li>Fornitura di informazioni<\/li>\n<li>Gestione candidature per impiego<\/li>\n<\/ul>\n<p><strong>3.A. Gestione ordini <\/strong><\/p>\n<ul>\n<li>Elaborazione di ordini di prodotti e servizi<\/li>\n<li>Contatti telefonici o via e-mail, se necessari, per l&#8217;erogazione dei servizi<\/li>\n<\/ul>\n<p><em>Elaborazione ordin<\/em><em>i<\/em><\/p>\n<p>Quando l&#8217;utente effettua un ordine, Kanters Special Products B.V. raccoglie i dati necessari per elaborarlo, quali ragione sociale, nome, cognome e indirizzo per la consegna. Inoltre, vengono conservati numero di telefono e indirizzo e-mail per eventuali contatti e aggiornamenti sullo stato dell&#8217;ordine.  <\/p>\n<p><strong>3.B. Marketing <\/strong><\/p>\n<ul>\n<li>Invio della newsletter via e-mail<\/li>\n<li>Invio postale di sondaggi per valutare la soddisfazione dei clienti<\/li>\n<li>Analisi e ottimizzazione delle attivit\u00e0 di marketing per offrire informazioni mirate su prodotti e servizi<\/li>\n<\/ul>\n<p><em>Newsletter<\/em><\/p>\n<p>Quando l&#8217;utente si iscrive alla newsletter, conserviamo nome e indirizzo e-mail per l&#8217;invio. Una o due volte all&#8217;anno inviamo un sondaggio sulla qualit\u00e0 della newsletter a tutti gli iscritti. Conserviamo inoltre informazioni sul settore di attivit\u00e0 per garantire comunicazioni pertinenti.  <\/p>\n<\/p>\n<p><em>Analisi<\/em><\/p>\n<p>Il sito web Kanters Special Products B.V. raccoglie dati tramite Google Analytics e l&#8217;indirizzo IP per migliorare il sito. Le informazioni riguardano la durata della visita e le pagine visitate dall&#8217;utente.   <\/p>\n<p><strong>3.C. Informazioni <\/strong><\/p>\n<ul>\n<li>Invio di informazioni su prodotti e servizi<\/li>\n<li>Comunicazioni istituzionali<\/li>\n<\/ul>\n<p><em>Richiesta di contatto<\/em><\/p>\n<p>Se l&#8217;utente richiede contatto tramite modulo sul sito, raccogliamo solo i dati necessari per assisterlo: nome, ragione sociale, CAP, e-mail e numero di telefono, per metterlo in contatto con il referente pi\u00f9 appropriato.  <\/p>\n<p><strong>3.D. Candidature per impiego <\/strong><\/p>\n<ul>\n<li>Gestione di candidature e curriculum<\/li>\n<\/ul>\n<p><em>Elaborazione candidature<\/em><\/p>\n<p>Le candidature e i curriculum sono trattati con la massima riservatezza e utilizzati esclusivamente per la valutazione dei candidati ed, eventualmente, per convocare i colloqui. Le candidature dei non selezionati vengono eliminate immediatamente, mentre quelle dei candidati convocati sono conservate e cancellate entro due mesi dal termine della selezione.   <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2314\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2314\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">4. Processo decisionale automatizzato<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2314\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2314\"><p>Kanters Special Products B.V. non prende decisioni automatizzate che possano avere effetti significativi sulle persone. Le altre decisioni vengono gestite tramite programmi o sistemi informatici senza intervento umano, ad esempio da un dipendente Kanters. I programmi e sistemi informatici utilizzati da Kanters Special Products B.V. includono:  <\/p>\n<ul>\n<li>MailChimp<\/li>\n<li>Exact Globe<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2315\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2315\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">5. Tempo di conservazione dei dati personali<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2315\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2315\"><p>Kanters Special Products B.V. conserva i dati personali dell&#8217;utente solo per il tempo necessario a perseguire le finalit\u00e0 per cui sono stati raccolti. I periodi di conservazione previsti per ciascuna categoria sono i seguenti: <\/p>\n<p>Ordini &gt; secondo gli obblighi di conservazione fiscale;<\/p>\n<p>Marketing &gt; fino a 2 anni dall&#8217;ultimo contatto;<\/p>\n<p>Newsletter* &gt; fino alla cancellazione dell&#8217;iscrizione;<\/p>\n<p>Informazioni &gt; fino a 2 anni dall&#8217;ultimo contatto;<\/p>\n<p>Al termine del rapporto di lavoro o della procedura di selezione, qualora non si concluda con un contratto, il Titolare del trattamento canceller\u00e0 entro 1 mese i seguenti dati:<\/p>\n<ul>\n<li>Dati personali di familiari;<\/li>\n<li>Curriculum e dati relativi al percorso formativo;<\/li>\n<li>Dati personali pubblicati sul sito del Titolare;<\/li>\n<li>Dati personali condivisi consensualmente per uso online (es. nome, indirizzo, dati del partner, nomi dei figli, foto di familiari e hobby).<\/li>\n<\/ul>\n<p>*Attivit\u00e0 di marketing speciale<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2316\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2316\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">6. Condivisione dei dati personali con terzi<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2316\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2316\"><p><strong>Cookie e tecnologie simili<\/strong><\/p>\n<p>Kanters Special Products B.V. utilizza esclusivamente cookie tecnici, funzionali e analitici che non ledono la privacy dell&#8217;utente.  Un cookie \u00e8 un piccolo file di testo memorizzato su computer, tablet o smartphone al primo accesso al sito. I cookie sono necessari per garantire il corretto funzionamento del sito, offrire un&#8217;esperienza d&#8217;uso ottimale, salvare le preferenze dell&#8217;utente e migliorare il sito web. L&#8217;utente pu\u00f2 disattivare i cookie modificando le impostazioni del browser e cancellare quelli gi\u00e0 memorizzati.     <em><\/p>\n<p><\/em><\/p>\n<p><strong>Google Analytics<\/strong><\/p>\n<p>Kanters Special Products B.V. utilizza Google Analytics per monitorare l&#8217;uso del sito e valutare l&#8217;efficacia degli annunci Google Ads nelle pagine di ricerca Google. I dati raccolti, incluso l&#8217;indirizzo IP, vengono trasmessi e archiviati da Google su server negli Stati Uniti. Per maggiori informazioni, si rimanda alle norme sulla privacy di Google e alle specifiche norme per Google Analytics, disponibili qui.   <\/p>\n<p>Google pu\u00f2 condividere tali dati con terze parti se richiesto dalla legge o se tali terze parti elaborano i dati per conto di Google. Tale processo esula dal controllo di Kanters Special Products B.V. <\/p>\n<p>Kanters Special Products B.V. non ha autorizzato Google a utilizzare i dati raccolti tramite Analytics per altri servizi Google.<\/p><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2317\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2317\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">7. Visione, rettifica o cancellazione dei dati<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2317\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2317\"><p>L&#8217;utente ha il diritto di accedere, rettificare o cancellare i propri dati personali. Pu\u00f2 inoltre revocare il consenso al trattamento o opporsi all&#8217;uso dei dati da parte di Kanters Special Products B.V., nonch\u00e9 esercitare il diritto alla portabilit\u00e0 dei dati, richiedendo di ricevere in formato digitale, direttamente o tramite un&#8217;organizzazione da lui indicata, i dati personali in nostro possesso.  <\/p>\n<p>Le richieste di accesso, rettifica, cancellazione, trasferimento, revoca del consenso o opposizione al trattamento possono essere inviate all&#8217;indirizzo email info@kanters.nl.<\/p>\n<p>Per verificare l&#8217;identit\u00e0 dell&#8217;utente, chiediamo di allegare una copia del documento d&#8217;identit\u00e0 con foto, area con codice a lettura ottica, numero documento e codice fiscale oscurati, per garantire la protezione della privacy. Risponderemo entro quattro settimane al massimo.   <\/p>\n<p>Kanters Special Products B.V. informa che l&#8217;utente pu\u00f2 presentare reclamo all&#8217;Autorit\u00e0 nazionale di controllo (Autoriteit Persoonsgegevens) tramite il seguente link: <a href=\"https:\/\/autoriteitpersoonsgegevens.nl\/nl\/contact-met-de-autoriteit-persoonsgegevens\/tip-ons\">https:\/\/autoriteitpersoonsgegevens.nl\/nl\/contact-met-de-autoriteit-persoonsgegevens\/tip-ons<\/a> <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2318\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2318\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">8. Protezione dei dati personali<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2318\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2318\"><p>Kanters Special Products B.V. tutela scrupolosamente i dati personali dell&#8217;utente, adottando misure idonee a prevenire abusi, perdite, accessi non autorizzati, divulgazioni o modifiche non autorizzate. Se l&#8217;utente sospetta una violazione della sicurezza dei propri dati o ne rileva un uso improprio, \u00e8 invitato a contattare il referente GDPR all&#8217;indirizzo info@kanters.nl. <\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Condizioni d&#8217;uso del presente sito web Kanters Special Products B.V.Con sede in:De Stater 325737 RV Lieshout Paesi Bassi, \u00e8 responsabile del trattamento dei dati personali come specificato nella presente Informativa sulla privacy. Dettagli di contatto:https:\/\/www.kantersanimalhealth.com\/De Stater 325737 RV LieshoutPaesi Bassi +31 (0) 499-425 600 Numero di registrazione camerale: 17076311 Il nostro referente per il regolamento [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-25891","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informativa sulla privacy - Kanters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativa sulla privacy - Kanters\" \/>\n<meta property=\"og:description\" content=\"Condizioni d&#8217;uso del presente sito web Kanters Special Products B.V.Con sede in:De Stater 325737 RV Lieshout Paesi Bassi, \u00e8 responsabile del trattamento dei dati personali come specificato nella presente Informativa sulla privacy. Dettagli di contatto:https:\/\/www.kantersanimalhealth.com\/De Stater 325737 RV LieshoutPaesi Bassi +31 (0) 499-425 600 Numero di registrazione camerale: 17076311 Il nostro referente per il regolamento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Kanters\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FlavourFamily\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T14:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/informativa-sulla-privacy\\\/\",\"url\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/informativa-sulla-privacy\\\/\",\"name\":\"Informativa sulla privacy - Kanters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/#website\"},\"datePublished\":\"2025-03-05T10:15:41+00:00\",\"dateModified\":\"2025-09-05T14:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/informativa-sulla-privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativa sulla privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/\",\"name\":\"Kanters\",\"description\":\"Special Products B.V.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/#organization\",\"name\":\"Flavour Family\",\"url\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Flavour Family\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FlavourFamily\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sulla privacy - Kanters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Informativa sulla privacy - Kanters","og_description":"Condizioni d&#8217;uso del presente sito web Kanters Special Products B.V.Con sede in:De Stater 325737 RV Lieshout Paesi Bassi, \u00e8 responsabile del trattamento dei dati personali come specificato nella presente Informativa sulla privacy. Dettagli di contatto:https:\/\/www.kantersanimalhealth.com\/De Stater 325737 RV LieshoutPaesi Bassi +31 (0) 499-425 600 Numero di registrazione camerale: 17076311 Il nostro referente per il regolamento [&hellip;]","og_url":"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/","og_site_name":"Kanters","article_publisher":"https:\/\/www.facebook.com\/FlavourFamily","article_modified_time":"2025-09-05T14:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/","url":"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/","name":"Informativa sulla privacy - Kanters","isPartOf":{"@id":"https:\/\/www.kantersanimalhealth.com\/it\/#website"},"datePublished":"2025-03-05T10:15:41+00:00","dateModified":"2025-09-05T14:03:40+00:00","breadcrumb":{"@id":"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kantersanimalhealth.com\/it\/informativa-sulla-privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kantersanimalhealth.com\/it\/"},{"@type":"ListItem","position":2,"name":"Informativa sulla privacy"}]},{"@type":"WebSite","@id":"https:\/\/www.kantersanimalhealth.com\/it\/#website","url":"https:\/\/www.kantersanimalhealth.com\/it\/","name":"Kanters","description":"Special Products B.V.","publisher":{"@id":"https:\/\/www.kantersanimalhealth.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kantersanimalhealth.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.kantersanimalhealth.com\/it\/#organization","name":"Flavour Family","url":"https:\/\/www.kantersanimalhealth.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.kantersanimalhealth.com\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Flavour Family"},"image":{"@id":"https:\/\/www.kantersanimalhealth.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FlavourFamily"]}]}},"_links":{"self":[{"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/pages\/25891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/comments?post=25891"}],"version-history":[{"count":11,"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/pages\/25891\/revisions"}],"predecessor-version":[{"id":30225,"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/pages\/25891\/revisions\/30225"}],"wp:attachment":[{"href":"https:\/\/www.kantersanimalhealth.com\/it\/wp-json\/wp\/v2\/media?parent=25891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}