{"id":30652,"date":"2025-10-22T09:32:58","date_gmt":"2025-10-22T08:32:58","guid":{"rendered":"https:\/\/www.kantersanimalhealth.com\/declaration-de-confidentialite\/"},"modified":"2025-10-22T09:33:06","modified_gmt":"2025-10-22T08:33:06","slug":"declaration-de-confidentialite","status":"publish","type":"page","link":"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/","title":{"rendered":"D\u00e9claration de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"30652\" class=\"elementor elementor-30652 elementor-7159\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1466aeb elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1466aeb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a945e06\" data-id=\"a945e06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88bfd72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88bfd72\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-832173c\" data-id=\"832173c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0beaf1c elementor-widget elementor-widget-heading\" data-id=\"0beaf1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00e9claration de confidentialit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85ae149 elementor-widget elementor-widget-heading\" data-id=\"85ae149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conditions d'utilisation de ce site<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29af564 elementor-widget elementor-widget-text-editor\" data-id=\"29af564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kanters Special Products B.V.<br \/>Situ\u00e9 \u00e0:<br \/>De Stater 32<br \/>5737 RV Lieshout<\/p><p>Pays-Bas, est responsable du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel tel qu&rsquo;\u00e9nonc\u00e9 dans la pr\u00e9sente D\u00e9claration de confidentialit\u00e9.<br \/><br \/><\/p><p>Coordonn\u00e9es:<br \/><a href=\"https:\/\/www.kanters.nl\/\">https:\/\/www.kanters.nl\/<\/a><br \/>De Stater 32<br \/>5737 RV Lieshout<br \/>Pays-Bas +31 (0) 499-425 600<\/p><p>Num\u00e9ro de chambre de commerce: 17076311<\/p><p>Notre contact pour le r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) est joignable \u00e0 <a href=\"mailto:info@kanters.nl\">info@kanters.nl<\/a.\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcf6fb8 elementor-widget elementor-widget-accordion\" data-id=\"dcf6fb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2311\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">1. Donn\u00e9es personnelles que nous traitons<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2311\"><p><strong>Kanters Special Products B.V. peut traiter des donn\u00e9es personnelles vous concernant, parce que :<\/strong><\/p>\n<ul>\n<li>vous faites appel aux services de Kanters Special Products B.V.,<\/li>\n<li>et\/ou parce que vous fournissez vous-m\u00eame ces donn\u00e9es \u00e0 Kanters Special Products B.V. apr\u00e8s avoir accept\u00e9 cette d\u00e9claration de confidentialit\u00e9 en remplissant un formulaire de contact sur le site.<\/li>\n<\/ul>\n<p><strong>Vous trouverez ci-dessous un aper\u00e7u des donn\u00e9es personnelles que nous traitons :<\/strong><\/p>\n<ul>\n<li>Coordonn\u00e9es de l&rsquo;entreprise<\/li>\n<li>Nom et pr\u00e9nom<\/li>\n<li>Num\u00e9ro de t\u00e9l\u00e9phone<\/li>\n<li>Num\u00e9ro de fax<\/li>\n<li>Adresse e-mail<\/li>\n<li>Donn\u00e9es relatives \u00e0 vos activit\u00e9s sur notre site<\/li>\n<li>Donn\u00e9es d&rsquo;adresse<\/li>\n<li>Adresse IP<\/li>\n<li>Secteur industriel<\/li>\n<li>Sous-secteur Historique des achats<\/li>\n<li>Num\u00e9ro BUN<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2312\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2312\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">2. Donn\u00e9es personnelles sp\u00e9ciales et\/ou sensibles que nous traitons<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2312\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2312\"><p>Notre site et\/ou service n&rsquo;a pas l&rsquo;intention de collecter des donn\u00e9es sur les visiteurs du site qui sont \u00e2g\u00e9s de moins de 16 ans. Sauf autorisation de leurs parents ou tuteur. Cependant, nous ne pouvons pas v\u00e9rifier si un visiteur a plus de 16 ans. Nous recommandons donc que les parents soient impliqu\u00e9s dans les activit\u00e9s en ligne de leurs enfants, afin d&#8217;emp\u00eacher que des donn\u00e9es soient collect\u00e9es sur les enfants sans autorisation parentale. Si vous \u00eates convaincu que nous avons collect\u00e9 des donn\u00e9es personnelles sur un mineur sans ce consentement, veuillez nous contacter \u00e0 <a href=\"mailto:info@kanters.nl\">info@kanters.nl<\/a> et nous supprimerons ces informations.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2313\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2313\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">3. Dans quel but et sur quelle base traitons-nous les donn\u00e9es personnelles ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2313\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2313\"><p>Kanters Special Products B.V. traite vos donn\u00e9es personnelles afin de vous contacter par t\u00e9l\u00e9phone si vous en faites la demande, et\/ou de vous contacter par \u00e9crit (par e-mail et\/ou par courrier) si vous n&rsquo;\u00eates pas joignable par t\u00e9l\u00e9phone dans le cas improbable.<\/p>\n<p>Kanters Special Products B.V. traite vos donn\u00e9es personnelles aux fins suivantes:<\/p>\n<ul>\n<li>Commande<\/li>\n<li>Marketing<\/li>\n<li>Informer<\/li>\n<li>Pour postuler \u00e0 un emploi<\/li>\n<\/ul>\n<p><strong>3.A. Commande<\/strong><\/p>\n<ul>\n<li>Traitement des commandes (produits et services)<\/li>\n<li>Appeler ou envoyer un e-mail si cela est n\u00e9cessaire \u00e0 l&rsquo;ex\u00e9cution de nos services<\/li>\n<\/ul>\n<p><p><em>Traitement de la commande<\/em><em>s<\/em><\/p>\n<\/p>\n<p>Si vous passez commande chez Kanters Special Products B.V., nous avons besoin de vos coordonn\u00e9es pour pouvoir traiter votre commande. Nous traitons le nom, le pr\u00e9nom, le nom et l&rsquo;adresse de votre entreprise pour livrer votre commande. Votre num\u00e9ro de t\u00e9l\u00e9phone et votre adresse e-mail sont stock\u00e9s pour vous contacter &#8211; si n\u00e9cessaire &#8211; et vous informer sur le traitement de votre commande.<\/p>\n<p><strong>3.B. Marketing<\/strong><\/p>\n<ul>\n<li>Envoi de notre newsletter par e-mail<\/li>\n<li>Envoi par e-mail dans le but de sonder votre satisfaction en tant que client par le biais d&rsquo;une enqu\u00eate de satisfaction client<\/li>\n<li>\n<li>Analyses et optimisations marketing dans le but de vous fournir les meilleures informations possibles sur nos produits et services<\/li>\n<\/li>\n<\/li>\n<\/li>\n<li>\n<li>\n<li>\n<li>\n<li>\n<li>< \n<br \/>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2314\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2314\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">4. Prise de d\u00e9cision automatis\u00e9e<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2314\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2314\"><p>Kanters Special Products B.V. ne prend pas de d\u00e9cisions sur la base d&rsquo;un traitement automatis\u00e9 concernant des questions qui peuvent avoir des cons\u00e9quences (consid\u00e9rables) pour les personnes. Il s&rsquo;agit de d\u00e9cisions prises par des programmes ou des syst\u00e8mes informatiques, sans qu&rsquo;un \u00eatre humain (par exemple un employ\u00e9 de Kanters Special Products B.V.) soit impliqu\u00e9. Kanters Special Products B.V. utilise les programmes ou syst\u00e8mes informatiques suivants :<\/p>\n<ul>\n<li>MailChimp<\/li>\n<li>Exact Globe<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2315\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2315\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">5. Combien de temps nous conservons les donn\u00e9es personnelles<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2315\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2315\"><p>Kanters Special Products B.V. enregistre vos donn\u00e9es personnelles plus longtemps que strictement n\u00e9cessaire pour atteindre les objectifs pour lesquels vos donn\u00e9es sont collect\u00e9es. Nous utilisons les p\u00e9riodes de conservation suivantes pour les (cat\u00e9gories) de donn\u00e9es personnelles suivantes:<\/p>\n<p>Commande &gt; conform\u00e9ment \u00e0 l&rsquo;obligation de stockage fiscal de l&rsquo;administration fiscale<\/p>\n<p>Marketing &gt; jusqu&rsquo;\u00e0 2 ans apr\u00e8s le dernier contact<\/p>\n<p>Newsletter* &gt; jusqu&rsquo;au moment o\u00f9 vous vous d\u00e9sabonnez de la newsletter<\/p>\n<p>Informer &gt; jusqu&rsquo;\u00e0 2 ans apr\u00e8s le dernier contact<\/p>\n<p>\u00c0 la fin du contrat de travail ou \u00e0 l&rsquo;issue d&rsquo;un processus de demande, processus qui n&rsquo;a pas conduit \u00e0 la conclusion d&rsquo;un contrat de travail, les donn\u00e9es suivantes seront supprim\u00e9es par le Responsable du traitement dans un d\u00e9lai d&rsquo;un mois:<\/p>\n<ul>\n<li>Donn\u00e9es personnelles des membres de la famille;<\/li>\n<li>Curriculum Vitae et d\u00e9tails de la formation suivie;<\/li>\n<li>Donn\u00e9es personnelles qui sont publi\u00e9es sur le site Web du Responsable du traitement.<\/li>\n<li>Donn\u00e9es personnelles (nom, adresse, coordonn\u00e9es du partenaire, noms des enfants, photographie de la famille, passe-temps du plaignant) qui ont \u00e9t\u00e9 mises \u00e0 disposition avec l&rsquo;autorisation \u00e0 des fins en ligne.<\/li>\n<\/ul>\n<p>*Activit\u00e9 marketing sp\u00e9ciale<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2316\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2316\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">6. Partage de donn\u00e9es personnelles avec des tiers<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2316\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2316\"><p><strong>Cookies ou techniques comparables<\/strong><\/p>\n<p>Kanters Special Products B.V. n&rsquo;utilise que des cookies techniques et fonctionnels, et des cookies analytiques qui ne portent pas atteinte \u00e0 votre vie priv\u00e9e. Un cookie est un petit fichier texte qui est stock\u00e9 sur votre ordinateur, tablette ou t\u00e9l\u00e9phone intelligent lors de votre premi\u00e8re visite sur ce site Web. Les cookies que nous utilisons sont n\u00e9cessaires au fonctionnement technique du site Web et \u00e0 votre facilit\u00e9 d&rsquo;utilisation. Ils garantissent le bon fonctionnement du site Web et nous permettent de m\u00e9moriser, par exemple, vos pr\u00e9f\u00e9rences. Ils nous permettent \u00e9galement d&rsquo;optimiser notre site Web. Vous pouvez vous d\u00e9sabonner des cookies en configurant votre navigateur Internet de mani\u00e8re \u00e0 ce qu&rsquo;il n&rsquo;enregistre plus de cookies. De plus, vous pouvez supprimer toutes les informations pr\u00e9c\u00e9demment stock\u00e9es en utilisant les param\u00e8tres de votre navigateur.<em><\/p>\n<p><\/em><\/p>\n<p><strong>Google Analytics<\/strong><\/p>\n<p>Kanters Special Products B.V. utilise Google Analytics pour suivre la fa\u00e7on dont les utilisateurs utilisent le site Web et l&rsquo;efficacit\u00e9 des annonces Google Adwords de Kanters Special Products B.V. sur les pages de r\u00e9sultats de recherche Google. Les informations ainsi obtenues, y compris l&rsquo;adresse de votre ordinateur (adresse IP), sont transmises \u00e0 Google et stock\u00e9es par Google sur des serveurs aux \u00c9tats-Unis. Veuillez lire la politique de confidentialit\u00e9 de Google pour plus d&rsquo;informations. Vous trouverez \u00e9galement la politique de confidentialit\u00e9 de Google Analytics ici.<\/p>\n<p>Google peut fournir ces informations \u00e0 des tiers si Google est l\u00e9galement tenu de le faire, ou dans la mesure o\u00f9 ces tiers traitent les informations pour le compte de Google. Kanters Special Products B.V. n&rsquo;a aucune influence sur cela.<\/p>\n<p>Kanters Special Products B.V. n&rsquo;a pas donn\u00e9 \u00e0 Google l&rsquo;autorisation d&rsquo;utiliser les informations Analytics obtenues via Kanters Special Products B.V. pour d&rsquo;autres services Google.<\/p>\n<p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2317\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2317\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">7. Affichage, modification ou suppression des donn\u00e9es<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2317\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2317\"><p>Vous avez le droit d&rsquo;inspecter, de corriger ou de supprimer vos donn\u00e9es \u00e0 caract\u00e8re personnel. En outre, vous avez le droit de retirer votre autorisation pour le traitement des donn\u00e9es ou de vous opposer au traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel par Kanters Special Products B.V. et vous avez le droit \u00e0 la portabilit\u00e9 des donn\u00e9es. Cela signifie que vous pouvez nous soumettre une demande \u00e9crite pour envoyer vos donn\u00e9es \u00e0 caract\u00e8re personnel en notre possession dans un fichier informatique \u00e0 vous-m\u00eame ou \u00e0 une autre organisation d\u00e9sign\u00e9e par vous.<\/p>\n<p>Vous pouvez envoyer une demande d&rsquo;inspection, de correction, de suppression, de transfert de vos donn\u00e9es \u00e0 caract\u00e8re personnel ou une demande de retrait de votre autorisation ou de votre opposition au traitement de vos donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 info@kanters.nl.<\/p>\n<p>Pour vous assurer que la demande d&rsquo;inspection est faite par vous, nous vous demandons d&rsquo;envoyer une copie de votre document d&rsquo;identit\u00e9 avec la demande. Dans cette copie, veuillez faire un noir sur votre photo de passeport, MRZ (zone lisible par machine, la bande avec des num\u00e9ros au bas du passeport), num\u00e9ro de passeport et num\u00e9ro de service citoyen, afin de prot\u00e9ger votre vie priv\u00e9e. Nous r\u00e9pondrons \u00e0 votre demande aussi rapidement que possible, mais dans un d\u00e9lai de quatre semaines.<\/p>\n<p>Kanters Special Products B.V. tient \u00e9galement \u00e0 souligner que vous avez la possibilit\u00e9 de d\u00e9poser une plainte aupr\u00e8s de l&rsquo;autorit\u00e9 de contr\u00f4le nationale, l&rsquo;Autoriteit Persoonsgevens. Vous pouvez le faire via le lien suivant: <a href=\"https:\/\/autoriteitpersoonsgevens.nl\/nl\/contact-met-de-autoriteit-persoonsgevens\/tip-ons\">https:\/\/autoriteitpersoonsgevens.nl\/nl\/contact-met-de-autoriteit-persoonsgevens\/tip-ons<\/a><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2318\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-2318\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">8. Comment nous s\u00e9curisons les donn\u00e9es personnelles<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2318\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-2318\"><p>Kanters Special Products B.V. prend la protection de vos donn\u00e9es au s\u00e9rieux et prend les mesures appropri\u00e9es pour pr\u00e9venir les abus, les pertes, les acc\u00e8s non autoris\u00e9s, les divulgations non d\u00e9sir\u00e9es et les modifications non autoris\u00e9es. Si vous avez l\u2019impression que vos donn\u00e9es ne sont pas correctement s\u00e9curis\u00e9es ou qu\u2019il existe des indices d\u2019abus, veuillez contacter notre interlocuteur RGPD via info@kanters.nl.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conditions d&rsquo;utilisation de ce site Kanters Special Products B.V.Situ\u00e9 \u00e0:De Stater 325737 RV Lieshout Pays-Bas, est responsable du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel tel qu&rsquo;\u00e9nonc\u00e9 dans la pr\u00e9sente D\u00e9claration de confidentialit\u00e9. Coordonn\u00e9es:https:\/\/www.kanters.nl\/De Stater 325737 RV LieshoutPays-Bas +31 (0) 499-425 600 Num\u00e9ro de chambre de commerce: 17076311 Notre contact pour le r\u00e8glement g\u00e9n\u00e9ral sur la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-30652","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration de confidentialit\u00e9 - Kanters<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration de confidentialit\u00e9 - Kanters\" \/>\n<meta property=\"og:description\" content=\"Conditions d&rsquo;utilisation de ce site Kanters Special Products B.V.Situ\u00e9 \u00e0:De Stater 325737 RV Lieshout Pays-Bas, est responsable du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel tel qu&rsquo;\u00e9nonc\u00e9 dans la pr\u00e9sente D\u00e9claration de confidentialit\u00e9. Coordonn\u00e9es:https:\/\/www.kanters.nl\/De Stater 325737 RV LieshoutPays-Bas +31 (0) 499-425 600 Num\u00e9ro de chambre de commerce: 17076311 Notre contact pour le r\u00e8glement g\u00e9n\u00e9ral sur la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Kanters\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FlavourFamily\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T08:33:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/declaration-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/declaration-de-confidentialite\\\/\",\"name\":\"D\u00e9claration de confidentialit\u00e9 - Kanters\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-10-22T08:32:58+00:00\",\"dateModified\":\"2025-10-22T08:33:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/declaration-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/declaration-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/declaration-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9claration de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/\",\"name\":\"Kanters\",\"description\":\"Special Products B.V.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/#organization\",\"name\":\"Flavour Family\",\"url\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Flavour Family\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kantersanimalhealth.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FlavourFamily\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration de confidentialit\u00e9 - Kanters","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration de confidentialit\u00e9 - Kanters","og_description":"Conditions d&rsquo;utilisation de ce site Kanters Special Products B.V.Situ\u00e9 \u00e0:De Stater 325737 RV Lieshout Pays-Bas, est responsable du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel tel qu&rsquo;\u00e9nonc\u00e9 dans la pr\u00e9sente D\u00e9claration de confidentialit\u00e9. Coordonn\u00e9es:https:\/\/www.kanters.nl\/De Stater 325737 RV LieshoutPays-Bas +31 (0) 499-425 600 Num\u00e9ro de chambre de commerce: 17076311 Notre contact pour le r\u00e8glement g\u00e9n\u00e9ral sur la [&hellip;]","og_url":"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/","og_site_name":"Kanters","article_publisher":"https:\/\/www.facebook.com\/FlavourFamily","article_modified_time":"2025-10-22T08:33:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/","url":"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/","name":"D\u00e9claration de confidentialit\u00e9 - Kanters","isPartOf":{"@id":"https:\/\/www.kantersanimalhealth.com\/fr\/#website"},"datePublished":"2025-10-22T08:32:58+00:00","dateModified":"2025-10-22T08:33:06+00:00","breadcrumb":{"@id":"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kantersanimalhealth.com\/fr\/declaration-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kantersanimalhealth.com\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9claration de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.kantersanimalhealth.com\/fr\/#website","url":"https:\/\/www.kantersanimalhealth.com\/fr\/","name":"Kanters","description":"Special Products B.V.","publisher":{"@id":"https:\/\/www.kantersanimalhealth.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kantersanimalhealth.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.kantersanimalhealth.com\/fr\/#organization","name":"Flavour Family","url":"https:\/\/www.kantersanimalhealth.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.kantersanimalhealth.com\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Flavour Family"},"image":{"@id":"https:\/\/www.kantersanimalhealth.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FlavourFamily"]}]}},"_links":{"self":[{"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/pages\/30652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/comments?post=30652"}],"version-history":[{"count":1,"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/pages\/30652\/revisions"}],"predecessor-version":[{"id":30653,"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/pages\/30652\/revisions\/30653"}],"wp:attachment":[{"href":"https:\/\/www.kantersanimalhealth.com\/fr\/wp-json\/wp\/v2\/media?parent=30652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}