{"id":27726,"date":"2025-06-15T06:12:56","date_gmt":"2025-06-15T05:12:56","guid":{"rendered":"https:\/\/www.kantersanimalhealth.com\/cuidado-5\/"},"modified":"2025-07-27T18:35:24","modified_gmt":"2025-07-27T17:35:24","slug":"cuidado-5","status":"publish","type":"page","link":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/","title":{"rendered":"Cuidado"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27726\" class=\"elementor elementor-27726 elementor-7662\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48bdbf0 elementor-section-full_width elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"48bdbf0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_bottom&quot;:&quot;waves&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M421.9,6.5c22.6-2.5,51.5,0.4,75.5,5.3c23.6,4.9,70.9,23.5,100.5,35.7c75.8,32.2,133.7,44.5,192.6,49.7\n\tc23.6,2.1,48.7,3.5,103.4-2.5c54.7-6,106.2-25.6,106.2-25.6V0H0v30.3c0,0,72,32.6,158.4,30.5c39.2-0.7,92.8-6.7,134-22.4\n\tc21.2-8.1,52.2-18.2,79.7-24.2C399.3,7.9,411.6,7.5,421.9,6.5z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6fb0ab\" data-id=\"c6fb0ab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe1aae0 elementor-widget elementor-widget-heading\" data-id=\"fe1aae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Aves de corral<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a08e437 elementor-widget elementor-widget-heading\" data-id=\"a08e437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Refuerzo respiratorio en los pollos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca97431 elementor-widget elementor-widget-text-editor\" data-id=\"ca97431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante periodos m\u00e1s calurosos, de estr\u00e9s o con reacciones a vacunas, los pollos necesitan cierto refuerzo respiratorio. Puede prestarles este refuerzo a sus aves utilizando productos con aceites esenciales como el eucalipto y el mentol. Esto despeja la tr\u00e1quea de mucosidad y alivia su respiraci\u00f3n. \u00a1Vea usted mismo c\u00f3mo funciona!   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd85857 elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fd85857\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"145\" height=\"181\" viewBox=\"0 0 145 181\" fill=\"none\"><path d=\"M72.6 181C53.3983 181 34.9831 173.372 21.4055 159.795C7.82783 146.217 0.199997 127.802 0.199997 108.6C0.199997 76.9069 24.7255 51.5579 46.2917 28.3265L72.6 0L98.9083 28.3265C120.474 51.5669 145 76.9159 145 108.6C145 127.802 137.372 146.217 123.795 159.795C110.217 173.372 91.8017 181 72.6 181Z\" fill=\"white\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M96.4123 99.7987H90.4691C90.3929 99.7987 90.3175 99.7835 90.2473 99.754C90.177 99.7246 90.1133 99.6814 90.0599 99.627C90.0065 99.5727 89.9645 99.5082 89.9363 99.4374C89.9081 99.3666 89.8943 99.2909 89.8957 99.2148V93.2716C89.893 93.1186 89.8302 92.9727 89.721 92.8655C89.6118 92.7582 89.4649 92.6982 89.3118 92.6982H82.5971C82.445 92.6982 82.2992 92.7586 82.1916 92.8661C82.0841 92.9737 82.0237 93.1196 82.0237 93.2716V99.2148C82.0237 99.3678 81.9636 99.5148 81.8563 99.624C81.7491 99.7332 81.6032 99.7959 81.4502 99.7987H75.4966C75.3446 99.7987 75.1987 99.8591 75.0911 99.9666C74.9836 100.074 74.9232 100.22 74.9232 100.372V107.087C74.9232 107.24 74.9832 107.387 75.0905 107.496C75.1978 107.605 75.3436 107.668 75.4966 107.671H81.4502C81.6023 107.671 81.7481 107.731 81.8557 107.839C81.9632 107.946 82.0237 108.092 82.0237 108.244V114.187C82.0237 114.339 82.0841 114.485 82.1916 114.593C82.2992 114.7 82.445 114.761 82.5971 114.761H89.3118C89.388 114.762 89.4637 114.748 89.5345 114.72C89.6052 114.692 89.6697 114.65 89.7241 114.596C89.7784 114.543 89.8216 114.479 89.8511 114.409C89.8805 114.339 89.8957 114.263 89.8957 114.187V108.244C89.8943 108.168 89.9081 108.093 89.9365 108.023C89.9648 107.953 90.007 107.889 90.0605 107.835C90.114 107.782 90.1778 107.74 90.248 107.711C90.3182 107.683 90.3934 107.669 90.4691 107.671H96.4123C96.5671 107.671 96.7156 107.609 96.8251 107.5C96.9346 107.39 96.9962 107.242 96.9962 107.087V100.372C96.9962 100.296 96.981 100.22 96.9515 100.15C96.9221 100.08 96.8789 100.016 96.8245 99.9629C96.7702 99.9095 96.7057 99.8675 96.6349 99.8393C96.5641 99.8111 96.4885 99.7973 96.4123 99.7987V99.7987Z\" fill=\"#EF7C00\"><\/path><path d=\"M73.6718 152.203C73.1548 152.199 72.6401 152.132 72.1391 152.004C38.2737 142.902 36.251 102.75 36.4074 90.6652C36.4271 89.1773 36.9976 87.7495 38.0086 86.6576C39.0196 85.5657 40.3993 84.8873 41.8813 84.7533C55.9363 83.4396 67.5514 75.6718 70.815 73.3467C71.6562 72.7316 72.6714 72.4 73.7135 72.4C74.7557 72.4 75.7708 72.7316 76.6121 73.3467C79.8443 75.6927 91.4803 83.4604 105.483 84.8159C106.965 84.9498 108.345 85.6283 109.356 86.7202C110.367 87.812 110.937 89.2398 110.957 90.7277C111.134 102.822 109.08 142.985 75.2567 152.067C74.7359 152.177 74.2036 152.222 73.6718 152.203V152.203ZM73.6718 77.6633C69.0529 80.9998 57.1353 88.559 42.3922 89.9457C42.1903 89.9615 42.0018 90.053 41.8646 90.2019C41.7273 90.3508 41.6513 90.5461 41.6519 90.7486C41.4747 101.874 43.2681 138.846 73.4841 146.968C73.6137 147.005 73.7508 147.005 73.8804 146.968C104.065 138.877 105.879 101.895 105.713 90.7486C105.713 90.5471 105.637 90.3531 105.499 90.2059C105.362 90.0587 105.173 89.9694 104.972 89.9562C90.2396 88.5694 78.3012 80.9893 73.6822 77.6633H73.6718Z\" fill=\"#EF7C00\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-873193f elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"873193f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"145\" height=\"181\" viewBox=\"0 0 145 181\" fill=\"none\"><path d=\"M72.4 181C53.1983 181 34.7831 173.372 21.2055 159.795C7.62784 146.217 0 127.802 0 108.6C0 76.9069 24.5255 51.5579 46.0917 28.3265L72.4 0L98.7084 28.3265C120.275 51.5669 144.8 76.9159 144.8 108.6C144.8 127.802 137.172 146.217 123.595 159.795C110.017 173.372 91.6017 181 72.4 181Z\" fill=\"white\"><\/path><path d=\"M101.364 100.892L98.4633 100.398C98.2317 99.7841 97.9799 99.1697 97.6979 98.5553L99.4101 96.1582C100.263 94.9749 100.665 93.5256 100.543 92.072C100.421 90.6183 99.7836 89.2562 98.7453 88.2315L94.9281 84.4142C93.9029 83.3805 92.543 82.7457 91.0922 82.6239C89.6414 82.5021 88.1947 82.9011 87.0115 83.7495L84.6144 85.4617C83.9597 85.1596 83.2949 84.8876 82.6 84.6358L82.1266 81.7955C81.8886 80.3633 81.1511 79.0617 80.0449 78.1214C78.9387 77.1811 77.5352 76.663 76.0834 76.6588H70.6949C69.244 76.6606 67.8407 77.1766 66.7342 78.1152C65.6278 79.0538 64.8899 80.3542 64.6517 81.7855L64.138 84.807C63.5236 85.0387 62.9092 85.3006 62.315 85.5826L59.9581 83.8804C58.9122 83.1325 57.6583 82.731 56.3725 82.7322C55.5611 82.7261 54.7568 82.8835 54.0075 83.195C53.2582 83.5065 52.5793 83.9657 52.0114 84.5452L48.184 88.3524C47.152 89.3831 46.5197 90.7469 46.3998 92.2006C46.2799 93.6542 46.6802 95.1032 47.5293 96.2891L49.2718 98.7366C48.9898 99.3409 48.738 99.9654 48.5164 100.59L45.6761 101.063C44.2429 101.301 42.9401 102.038 41.9981 103.144C41.0562 104.25 40.5359 105.654 40.5293 107.106V112.495C40.5335 113.947 41.0516 115.35 41.9919 116.456C42.9322 117.563 44.2338 118.3 45.666 118.538L48.6876 119.042C48.9193 119.666 49.1711 120.281 49.4531 120.875L47.6502 123.272C46.7978 124.455 46.3955 125.903 46.5155 127.356C46.6355 128.809 47.27 130.172 48.3049 131.199L52.1221 135.016C53.1504 136.044 54.5097 136.675 55.9588 136.797C57.4079 136.918 58.8534 136.523 60.0387 135.681L62.4862 133.938C63.0402 134.18 63.6143 134.422 64.1985 134.633L64.6819 137.544C64.9161 138.978 65.6525 140.282 66.7595 141.223C67.8666 142.164 69.2722 142.681 70.7251 142.681H76.1841C77.6365 142.678 79.041 142.161 80.1476 141.22C81.2542 140.28 81.9912 138.977 82.2273 137.544L82.7208 134.643C83.3453 134.412 83.9597 134.15 84.564 133.878L86.941 135.58C88.1292 136.428 89.5794 136.827 91.0342 136.707C92.4891 136.588 93.8543 135.956 94.8878 134.925L98.695 131.108C99.7292 130.081 100.365 128.721 100.489 127.269C100.612 125.817 100.216 124.368 99.3698 123.181L97.6475 120.774C97.9295 120.17 98.1914 119.555 98.413 118.931L101.314 118.447C102.749 118.214 104.054 117.477 104.996 116.371C105.939 115.264 106.458 113.858 106.46 112.404V106.986C106.491 105.526 105.991 104.104 105.054 102.984C104.117 101.864 102.806 101.12 101.364 100.892V100.892ZM101.727 112.354C101.729 112.687 101.612 113.009 101.398 113.264C101.184 113.519 100.886 113.689 100.558 113.744L96.3482 114.449C95.8758 114.521 95.4337 114.726 95.0734 115.04C94.7132 115.354 94.4497 115.763 94.3137 116.222C93.926 117.463 93.4271 118.666 92.823 119.817C92.6055 120.231 92.5072 120.696 92.5393 121.162C92.5713 121.628 92.7323 122.076 93.0043 122.456L95.482 125.931C95.6777 126.203 95.7699 126.536 95.7422 126.87C95.7145 127.204 95.5687 127.518 95.3309 127.754L91.5137 131.561C91.3815 131.693 91.2244 131.798 91.0515 131.869C90.8786 131.94 90.6933 131.975 90.5065 131.974C90.2183 131.976 89.9367 131.888 89.7007 131.722L86.2561 129.224C85.8733 128.951 85.4219 128.789 84.9523 128.757C84.4827 128.725 84.0135 128.824 83.5971 129.043C82.443 129.641 81.2401 130.14 80.0014 130.534C79.5511 130.672 79.1488 130.934 78.8407 131.291C78.5325 131.647 78.3309 132.083 78.2589 132.548L77.5438 136.758C77.484 137.078 77.3163 137.367 77.0689 137.578C76.8214 137.789 76.5091 137.908 76.1841 137.917H70.7755C70.4418 137.916 70.1191 137.798 69.8646 137.582C69.6101 137.366 69.4403 137.067 69.3855 136.738L68.6906 132.538C68.6153 132.074 68.4125 131.64 68.1048 131.284C67.7971 130.928 67.3967 130.665 66.9481 130.524C65.7492 130.143 64.5837 129.665 63.4632 129.094C63.1032 128.904 62.7017 128.807 62.2949 128.812C61.7686 128.81 61.2549 128.972 60.8243 129.275L57.2991 131.793C57.0682 131.952 56.794 132.036 56.5135 132.035C56.3267 132.035 56.1416 131.999 55.9688 131.928C55.796 131.858 55.6388 131.753 55.5063 131.622L51.679 127.804C51.4446 127.57 51.3008 127.261 51.2731 126.931C51.2454 126.6 51.3357 126.271 51.5279 126.001L53.9855 122.577C54.2668 122.196 54.4333 121.742 54.4654 121.269C54.4975 120.796 54.3939 120.324 54.1668 119.908C53.5607 118.76 53.0584 117.56 52.666 116.322C52.5221 115.876 52.2579 115.478 51.9025 115.173C51.5471 114.867 51.1143 114.665 50.6516 114.59L46.3912 113.865C46.0621 113.81 45.7631 113.64 45.5473 113.386C45.3315 113.131 45.213 112.808 45.2128 112.475V107.096C45.2126 106.762 45.3308 106.437 45.5464 106.181C45.762 105.925 46.0612 105.753 46.3912 105.696L50.5408 105.001C51.0084 104.927 51.4453 104.722 51.8017 104.41C52.158 104.098 52.4191 103.692 52.5552 103.239C52.9403 101.997 53.4323 100.79 54.0258 99.633C54.2435 99.2215 54.342 98.7573 54.3099 98.2928C54.2779 97.8283 54.1167 97.382 53.8445 97.0042L51.3466 93.479C51.1517 93.2084 51.0598 92.877 51.0875 92.5447C51.1152 92.2123 51.2607 91.9007 51.4977 91.6661L55.325 87.8488C55.4575 87.7171 55.6147 87.6128 55.7875 87.542C55.9603 87.4711 56.1454 87.435 56.3322 87.4358C56.6175 87.4329 56.8963 87.5211 57.1279 87.6876L60.5725 90.1653C60.9998 90.4769 61.5143 90.646 62.0431 90.6488C62.4609 90.6444 62.8716 90.5408 63.2416 90.3466C64.3866 89.7314 65.5872 89.2256 66.8272 88.8358C67.2745 88.6939 67.6734 88.4303 67.9794 88.0746C68.2853 87.7188 68.4862 87.2849 68.5596 86.8214L69.2848 82.561C69.3377 82.231 69.5069 81.9308 69.7618 81.7147C70.0167 81.4986 70.3405 81.3808 70.6747 81.3826H76.0633C76.399 81.3848 76.7232 81.5052 76.9792 81.7224C77.2352 81.9397 77.4065 82.2401 77.4633 82.5711L78.1582 86.7207C78.2318 87.1887 78.4364 87.6262 78.7483 87.9827C79.0602 88.3392 79.4668 88.6001 79.9208 88.7351C81.2095 89.1374 82.4599 89.6531 83.6575 90.2761C84.0706 90.4948 84.5365 90.5937 85.0028 90.5617C85.4691 90.5296 85.9171 90.3679 86.2964 90.0948L89.7914 87.6071C90.0208 87.4449 90.296 87.3602 90.577 87.3653C90.7638 87.3645 90.9489 87.4006 91.1217 87.4715C91.2945 87.5423 91.4517 87.6466 91.5842 87.7783L95.4115 91.5956C95.6462 91.8298 95.7895 92.1403 95.8153 92.4709C95.8412 92.8016 95.748 93.1305 95.5525 93.3984L93.0748 96.8733C92.8028 97.253 92.6418 97.701 92.6098 98.167C92.5778 98.633 92.676 99.0988 92.8935 99.5121C93.4887 100.672 93.9807 101.882 94.364 103.128C94.5044 103.577 94.7673 103.978 95.1232 104.286C95.479 104.594 95.9138 104.796 96.3784 104.87L100.589 105.575C100.913 105.631 101.207 105.8 101.418 106.053C101.628 106.306 101.741 106.626 101.737 106.955L101.727 112.354Z\" fill=\"#404040\"><\/path><path d=\"M73.4647 96.7826C70.875 96.7826 68.3435 97.5505 66.1903 98.9893C64.0371 100.428 62.3588 102.473 61.3678 104.865C60.3768 107.258 60.1175 109.891 60.6227 112.431C61.1279 114.971 62.375 117.304 64.2061 119.135C66.0373 120.966 68.3704 122.213 70.9103 122.718C73.4502 123.223 76.0829 122.964 78.4754 121.973C80.8679 120.982 82.9129 119.304 84.3516 117.151C85.7904 114.997 86.5583 112.466 86.5583 109.876C86.5583 106.404 85.1788 103.073 82.7233 100.618C80.2677 98.1621 76.9373 96.7826 73.4647 96.7826V96.7826ZM73.4647 118.276C71.8093 118.276 70.1911 117.785 68.8147 116.866C67.4383 115.946 66.3655 114.639 65.732 113.109C65.0985 111.58 64.9328 109.897 65.2557 108.274C65.5787 106.65 66.3758 105.159 67.5464 103.988C68.7169 102.817 70.2083 102.02 71.8318 101.697C73.4554 101.374 75.1383 101.54 76.6677 102.174C78.1971 102.807 79.5043 103.88 80.424 105.256C81.3436 106.633 81.8345 108.251 81.8345 109.906C81.8212 112.118 80.9339 114.235 79.366 115.796C77.798 117.356 75.6768 118.233 73.4647 118.236V118.276Z\" fill=\"#404040\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b4cee8e\" data-id=\"b4cee8e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72897aa9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72897aa9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5cee40b9\" data-id=\"5cee40b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e6b69d1 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2e6b69d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#uitdaging\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Desaf\u00edos\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  akar-v1-question\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#uitdaging\" >\n\t\t\t\t\t\t\tDesaf\u00edos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-55c374d4\" data-id=\"55c374d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38a71be1 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"38a71be1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#herken\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"C\u00f3mo detectarlo\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  akar-v1-search\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#herken\" >\n\t\t\t\t\t\t\tC\u00f3mo detectarlo\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-25436f35\" data-id=\"25436f35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1329ad elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e1329ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#oorzaak\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Causa y efecto\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  akar-v1-thunder\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#oorzaak\" >\n\t\t\t\t\t\t\tCausa y efecto\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-167347a9\" data-id=\"167347a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-626063c0 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"626063c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#oplossing\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Soluci\u00f3n\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  akar-v1-circle-check\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#oplossing\" >\n\t\t\t\t\t\t\tSoluci\u00f3n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-398954b8\" data-id=\"398954b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6360322d elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6360322d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#producten\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Productos\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  akar-v1-shipping-box-v1\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#producten\" >\n\t\t\t\t\t\t\tProductos\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e9b48fa elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e9b48fa\" data-element_type=\"section\" data-e-type=\"section\" id=\"uitdaging\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-703a57b9\" data-id=\"703a57b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf7cdd elementor-widget elementor-widget-image\" data-id=\"cf7cdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2022\/05\/Beeld_kuiken_Aeroforte-1024x768.png\" class=\"attachment-large size-large wp-image-30624\" alt=\"heat stress in poultry asks for Aeroforte\" srcset=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2022\/05\/Beeld_kuiken_Aeroforte-1024x768.png 1024w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2022\/05\/Beeld_kuiken_Aeroforte-370x278.png 370w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2022\/05\/Beeld_kuiken_Aeroforte-768x576.png 768w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2022\/05\/Beeld_kuiken_Aeroforte.png 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7f2bea6b\" data-id=\"7f2bea6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35c6fd79 elementor-widget elementor-widget-heading\" data-id=\"35c6fd79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Desaf\u00edos<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68f806ec elementor-widget elementor-widget-heading\" data-id=\"68f806ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Los problemas respiratorios pueden ser un gran problema en los pollos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cee3da7 elementor-widget elementor-widget-text-editor\" data-id=\"2cee3da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La dificultad respiratoria (disnea) no es agradable. Tanto las personas como los animales experimentan compresi\u00f3n tor\u00e1cica en d\u00edas calurosos cuando hay humedad alta. Debido a la gran densidad de individuos en los establos, los animales no siempre tienen la oportunidad de encontrar un lugar m\u00e1s fresco. Adem\u00e1s, los resfriados tambi\u00e9n pueden originar problemas respiratorios en los pollos. Esto les resulta molesto y hace que las aves coman menos y por tanto no crezcan o no pongan huevos. A menudo se observa despu\u00e9s de vacunarlos. \u00bfQu\u00e9 podemos hacer al respecto? Kanters se lo explica.       <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4129564c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4129564c\" data-element_type=\"section\" data-e-type=\"section\" id=\"herken\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4af1793d\" data-id=\"4af1793d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78f474da elementor-widget elementor-widget-heading\" data-id=\"78f474da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">C\u00f3mo detectarlo<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3de20742 elementor-widget elementor-widget-heading\" data-id=\"3de20742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo saber si un pollo necesita ayuda?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43569c84 elementor-widget elementor-widget-text-editor\" data-id=\"43569c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cuando camina por la nave, es f\u00e1cil reconocer los problemas respiratorios en las aves. Los pollos buscan refrescarse apoy\u00e1ndose contra la pared fr\u00eda y mantienen los picos abiertos para librarse del calor o para obtener m\u00e1s ox\u00edgeno. En caso de reacciones a vacunas, pueden observarse mucosidades en las narinas encima del pico. Esto hace que los animales resuellen y que pierdan el apetito. Es necesario prevenirlo.    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cda8cb1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cda8cb1\" data-element_type=\"section\" data-e-type=\"section\" id=\"oorzaak\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfa34aa\" data-id=\"bfa34aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d0aa0d elementor-widget elementor-widget-heading\" data-id=\"1d0aa0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Causa y efecto<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e97031 elementor-widget elementor-widget-heading\" data-id=\"2e97031\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Los pollos aquejados de disnea tienden a morir<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58ed3ad elementor-widget elementor-widget-text-editor\" data-id=\"58ed3ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Por la tarde, la humedad en la nace puede aumentar. Si se combina con altas temperaturas vespertinas, crecer\u00e1 la compresi\u00f3n tor\u00e1cica en los pollos.  <br>Es importante ventilar m\u00e1s para sacar el calor de la nave, pero esto tambi\u00e9n aumenta la humedad. Una situaci\u00f3n dif\u00edcil para cualquier ganadero. Afortunadamente, Kanters tiene la soluci\u00f3n.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-202a7f23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"202a7f23\" data-element_type=\"section\" data-e-type=\"section\" id=\"oplossing\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7498b083\" data-id=\"7498b083\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46a96438 elementor-widget elementor-widget-heading\" data-id=\"46a96438\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\nSoluci\u00f3n\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7c6fd6 elementor-widget elementor-widget-heading\" data-id=\"6d7c6fd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Aeroforte alivia los problemas respiratorios<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-378f409e elementor-widget elementor-widget-text-editor\" data-id=\"378f409e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los aceites esenciales son la soluci\u00f3n a los problemas respiratorios. Procuran un alivio para la respiraci\u00f3n. <\/p><p>En Kanters podr\u00e1 encontrar suplementos para el agua de bebida que contienen aceites esenciales. Aeroforte puede administrarse a trav\u00e9s del agua de bebida, de modo que los animales se aliviar\u00e1n r\u00e1pido de la falta de ox\u00edgeno. Aeroforte tambi\u00e9n se puede pulverizar por el establo. Las finas gotas se inhalan profundamente y proporcionan alivio respiratorio.   <\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31048f06\" data-id=\"31048f06\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bb16138 elementor-widget elementor-widget-image\" data-id=\"1bb16138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/12\/Foto-binnenzijde-folder-Aeroforte-Pluimvee-min-1024x683.jpg\" class=\"attachment-large size-large wp-image-30621\" alt=\"\" srcset=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/12\/Foto-binnenzijde-folder-Aeroforte-Pluimvee-min-1024x683.jpg 1024w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/12\/Foto-binnenzijde-folder-Aeroforte-Pluimvee-min-370x247.jpg 370w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/12\/Foto-binnenzijde-folder-Aeroforte-Pluimvee-min-768x512.jpg 768w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/12\/Foto-binnenzijde-folder-Aeroforte-Pluimvee-min-1536x1024.jpg 1536w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/12\/Foto-binnenzijde-folder-Aeroforte-Pluimvee-min-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47d8534 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47d8534\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1b62004\" data-id=\"1b62004\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcb6094 elementor-widget elementor-widget-heading\" data-id=\"fcb6094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Referenties<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-549a0b6 elementor-widget elementor-widget-testimonial\" data-id=\"549a0b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">\"Aeroforte geeft mijn kippen net dat beetje extra ondersteuning, zodat ze makkelijk door de hete dagen komen. Dankzij de Optimus  <\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"380\" height=\"265\" src=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/Team-5.png\" class=\"attachment-full size-full wp-image-5949\" alt=\"\" srcset=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/Team-5.png 380w, https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/Team-5-370x258.png 370w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Klaas Timmer<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Vleeskuikenhouder (110.000 vleeskuikens) te Meerkerk<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ea89b8 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"6ea89b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"\/category\/referenties\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  akar-v1-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Naar referenties<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5335d8d\" data-id=\"5335d8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9764df5 elementor-widget elementor-widget-image\" data-id=\"9764df5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/5APBLfC2hUs.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d30ff9c elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"d30ff9c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f920288\" data-id=\"f920288\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-171c0c7 elementor-widget elementor-widget-heading\" data-id=\"171c0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Los animales sanos proporcionan satisfacci\u00f3n laboral y rentabilidad<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0faa0bc elementor-widget elementor-widget-heading\" data-id=\"0faa0bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Estaremos encantados de visitarle para determinar qu\u00e9 puede hacer Aeroforte por sus animales. Kanters dispone de una soluci\u00f3n adecuada para cada especie de animal, edad del mismo y entorno de cr\u00eda.  \u00bfDesea m\u00e1s informaci\u00f3n o concertar una cita?<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b6962c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7b6962c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kantersanimalhealth.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">P\u00f3ngase en contacto con nosotros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-877e5cc elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"877e5cc\" data-element_type=\"section\" data-e-type=\"section\" id=\"producten\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b4f9cf\" data-id=\"2b4f9cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aac2820 k-products pp-info-box-above-title elementor-widget elementor-widget-pp-info-box-carousel\" data-id=\"aac2820\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;equal_height_boxes&quot;:&quot;yes&quot;}\" data-widget_type=\"pp-info-box-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-container pp-info-box-carousel pp-swiper-slider swiper\" data-slider-settings=\"{&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;slides_per_view&quot;:1,&quot;space_between&quot;:24,&quot;auto_height&quot;:true,&quot;loop&quot;:&quot;&quot;,&quot;slides_per_view_mobile&quot;:1,&quot;space_between_mobile&quot;:10,&quot;slides_per_view_tablet&quot;:2,&quot;space_between_tablet&quot;:10}\">\n\t\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"pp-info-box swiper-slide\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-icon-wrap\">\n\t\t\t\t\t\t\t\t<span class=\"pp-info-box-icon pp-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2022\/01\/Aeroforte.png\" alt=\"Aeroforte\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"pp-info-box-content\">\n\t\t\t\t\t\t\t\t<div class=\"pp-info-box-title-wrap\">\n\t\t\t\t\t\t\t<div class=\"pp-info-box-title-container\">\n\t\t\t\t\t<h5 class=\"pp-info-box-title\">\n\t\t\t\t\t\tAeroforte\u00ae\t\t\t\t\t<\/h5>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-description\">\n\t\t\t\t\t\t\t\t<p>Refresca la respiraci\u00f3n<\/p><ul><li>Tiene un efecto positivo frente a las consecuencias del estr\u00e9s t\u00e9rmico por calor<\/li><li>Estimula la disoluci\u00f3n de la sobreproducci\u00f3n de mucosidades<\/li><li>Ayuda a mitigar la producci\u00f3n de moco por reacciones a las vacunas<\/li><li>Alivia la respiraci\u00f3n<\/li><li>El mentol tiene un efecto refrescante en el animal<\/li><\/ul>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-info-box-footer\">\n\t\t\t\t\t\t\t\t<a class=\"pp-info-box-button elementor-button elementor-size-md\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\thref=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEzNDEzIiwidG9nZ2xlIjpmYWxzZX0%3D\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-button-text\">\n\t\t\t\t\t\t\t\t\t\t\tDescargar la informaci\u00f3n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ebff321\" data-id=\"ebff321\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0072683 elementor-widget elementor-widget-heading\" data-id=\"0072683\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Productos para solucionar cualquier dificultad<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc91d7b elementor-widget elementor-widget-heading\" data-id=\"cc91d7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La soluci\u00f3n para una respiraci\u00f3n despejada<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8e3a5f elementor-widget elementor-widget-text-editor\" data-id=\"f8e3a5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En Kanters encontrar\u00e1 productos para mejorar la salud de sus animales, para cada especie de animal y entorno de cr\u00eda. Haga clic a continuaci\u00f3n para obtener m\u00e1s informaci\u00f3n sobre nuestros productos, y para descargar los informes de investigaci\u00f3n y acceder a la documentaci\u00f3n sobre su uso y efectos. <\/p><p>\u00bfDesea ir directamente al formulario de pedidos?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f28047f elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"f28047f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/kantersanimalhealth.com\/ordering-products\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Al formulario de pedidos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bc6730 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"8bc6730\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/kantersanimalhealth.com\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eci  akar-v1-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">P\u00f3ngase en contacto con nosotros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aves de corral Refuerzo respiratorio en los pollos Durante periodos m\u00e1s calurosos, de estr\u00e9s o con reacciones a vacunas, los pollos necesitan cierto refuerzo respiratorio. Puede prestarles este refuerzo a sus aves utilizando productos con aceites esenciales como el eucalipto y el mentol. Esto despeja la tr\u00e1quea de mucosidad y alivia su respiraci\u00f3n. \u00a1Vea usted [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":27565,"parent":27819,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27726","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuidado - Kanters<\/title>\n<meta name=\"description\" content=\"Refuerzo respiratorio en pollos. Descubra Aeroforte: para aliviar problemas respiratorios en pollos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuidado - Kanters\" \/>\n<meta property=\"og:description\" content=\"Refuerzo respiratorio en pollos. Descubra Aeroforte: para aliviar problemas respiratorios en pollos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Kanters\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FlavourFamily\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-27T17:35:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/\",\"url\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/\",\"name\":\"Cuidado - Kanters\",\"isPartOf\":{\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png\",\"datePublished\":\"2025-06-15T05:12:56+00:00\",\"dateModified\":\"2025-07-27T17:35:24+00:00\",\"description\":\"Refuerzo respiratorio en pollos. Descubra Aeroforte: para aliviar problemas respiratorios en pollos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#primaryimage\",\"url\":\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png\",\"contentUrl\":\"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png\",\"width\":1920,\"height\":1163},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kantersanimalhealth.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aves de corral\",\"item\":\"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cuidado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/#website\",\"url\":\"https:\/\/www.kantersanimalhealth.com\/es\/\",\"name\":\"Kanters\",\"description\":\"Special Products B.V.\",\"publisher\":{\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kantersanimalhealth.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/#organization\",\"name\":\"Flavour Family\",\"url\":\"https:\/\/www.kantersanimalhealth.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Flavour Family\"},\"image\":{\"@id\":\"https:\/\/www.kantersanimalhealth.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FlavourFamily\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuidado - Kanters","description":"Refuerzo respiratorio en pollos. Descubra Aeroforte: para aliviar problemas respiratorios en pollos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/","og_locale":"es_ES","og_type":"article","og_title":"Cuidado - Kanters","og_description":"Refuerzo respiratorio en pollos. Descubra Aeroforte: para aliviar problemas respiratorios en pollos.","og_url":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/","og_site_name":"Kanters","article_publisher":"https:\/\/www.facebook.com\/FlavourFamily","article_modified_time":"2025-07-27T17:35:24+00:00","og_image":[{"width":1920,"height":1163,"url":"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/","url":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/","name":"Cuidado - Kanters","isPartOf":{"@id":"https:\/\/www.kantersanimalhealth.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#primaryimage"},"image":{"@id":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png","datePublished":"2025-06-15T05:12:56+00:00","dateModified":"2025-07-27T17:35:24+00:00","description":"Refuerzo respiratorio en pollos. Descubra Aeroforte: para aliviar problemas respiratorios en pollos.","breadcrumb":{"@id":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#primaryimage","url":"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png","contentUrl":"https:\/\/www.kantersanimalhealth.com\/wp-content\/uploads\/2021\/09\/hQV3s7J6eM4.png","width":1920,"height":1163},{"@type":"BreadcrumbList","@id":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/cuidado-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kantersanimalhealth.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aves de corral","item":"https:\/\/www.kantersanimalhealth.com\/es\/aves-de-corral\/"},{"@type":"ListItem","position":3,"name":"Cuidado"}]},{"@type":"WebSite","@id":"https:\/\/www.kantersanimalhealth.com\/es\/#website","url":"https:\/\/www.kantersanimalhealth.com\/es\/","name":"Kanters","description":"Special Products B.V.","publisher":{"@id":"https:\/\/www.kantersanimalhealth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kantersanimalhealth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.kantersanimalhealth.com\/es\/#organization","name":"Flavour Family","url":"https:\/\/www.kantersanimalhealth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kantersanimalhealth.com\/es\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Flavour Family"},"image":{"@id":"https:\/\/www.kantersanimalhealth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FlavourFamily"]}]}},"_links":{"self":[{"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/pages\/27726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/comments?post=27726"}],"version-history":[{"count":1,"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/pages\/27726\/revisions"}],"predecessor-version":[{"id":27727,"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/pages\/27726\/revisions\/27727"}],"up":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/pages\/27819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/media\/27565"}],"wp:attachment":[{"href":"https:\/\/www.kantersanimalhealth.com\/es\/wp-json\/wp\/v2\/media?parent=27726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}